{"id":6094,"date":"2023-08-27T16:11:00","date_gmt":"2023-08-27T16:11:00","guid":{"rendered":"https:\/\/webs.ddca.se\/emprenderymas\/?p=6094"},"modified":"2022-01-05T08:22:32","modified_gmt":"2022-01-05T08:22:32","slug":"como-librarse-de-los-peores-clientes-colaboradores-y-proveedores","status":"publish","type":"post","link":"https:\/\/webs.ddca.se\/emprenderymas\/2023\/08\/27\/como-librarse-de-los-peores-clientes-colaboradores-y-proveedores\/","title":{"rendered":"C\u00f3mo librarse de los peores clientes, colaboradores y proveedores"},"content":{"rendered":"\n<p>Si uno es responsable de un negocio, tarde o temprano lo m\u00e1s probable es que cuente con clientes, proveedores o colaboradores que son insufribles, insoportables. Es un gaje del oficio y es pr\u00e1cticamente inevitable: con cuantas m\u00e1s personas te relaciones, mayor es la probabilidad de dar con una que no cuenta la simpat\u00eda y la amabilidad entre sus prioridades. Uno puede tolerarlos durante un tiempo, pero llegado un punto ya no hay quien los aguante y pueden convertir nuestra vida empresarial -o nuestra vida a secas- en una pesadilla.<br>Me refiero a aquellos clientes, proveedores o colaboradores que nunca est\u00e1n contentos, que protestan por protestar, que siempre buscan alguna pega incluso cuando todo est\u00e1 perfecto, que tratan de negociar los precios m\u00e1s all\u00e1 de los razonable\u2026 En fin, esas personas que te hacen la vida imposible y que tratas de soportar sin decir nada.<br>Sin embargo, esas personas absorben nuestra energ\u00eda. Quitan tiempo y perjudican tu serenidad, dos aspectos que podr\u00edas invertir en clientes m\u00e1s amables, en proveedores m\u00e1s fiables o en socios con gran potencial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un m\u00e9todo eficaz en solo dos pasos<\/h3>\n\n\n\n<p><br>Pues bien, por suerte para nosotros, la soluci\u00f3n es relativamente sencilla. \u00danicamente hay que armarse de valor y seguir este proceso de solo dos etapas:<\/p>\n\n\n\n<p><br>-Prop\u00f3n una reuni\u00f3n de actualizaci\u00f3n en el que uno de los puntos del d\u00eda sea la mejora de vuestras relaciones. Durante esa reuni\u00f3n, abordar\u00e1s lo que funciona y, sobre todo, lo que no funciona.<\/p>\n\n\n\n<p><br>-Si despu\u00e9s de esa reuni\u00f3n constatas que no se produce ning\u00fan cambio de comportamiento, despide a la persona en cuesti\u00f3n -si es que se trata de un colaborador o proveedor-, o expl\u00edcale amablemente que ya no deseas tenerlo como cliente.<\/p>\n\n\n\n<p><br>Llegados a ese punto, pueden ocurrir dos cosas. <\/p>\n\n\n\n<p>1) Que el cliente, proveedor o colaborador se d\u00e9 cuenta de que ha ido demasiado lejos y cambiar\u00e1 de pronto porque valora tus productos y servicios o porque quiere seguir trabajando contigo. <\/p>\n\n\n\n<p>2) Que siga como siempre, en cuyo caso ir\u00e1s a la b\u00fasqueda de otros clientes o proveedores con los que trabajes m\u00e1s a gusto.<\/p>\n\n\n\n<p><br>En cualquiera de esos dos casos, comprobar\u00e1s enseguida que trabajas con m\u00e1s serenidad, es decir, con m\u00e1s eficacia y, por tanto, de manera m\u00e1s rentable. En ese caso, seguramente te preguntes c\u00f3mo es que no has puesto en pr\u00e1ctica este sistema antes para deshacerte de tus m\u00e1s insufribles clientes y colaboradores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si uno es responsable de un negocio, tarde o temprano lo m\u00e1s probable es que cuente con clientes, proveedores o colaboradores que son insufribles, insoportables. Es un gaje del oficio y es pr\u00e1cticamente inevitable: con cuantas m\u00e1s personas te relaciones, mayor es la probabilidad de dar con una que no cuenta la simpat\u00eda y la amabilidad entre sus prioridades.<\/p>\n","protected":false},"author":3,"featured_media":6095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[344],"tags":[307,155,310],"class_list":["post-6094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productividad","tag-empresa","tag-featured","tag-tips"],"_links":{"self":[{"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/posts\/6094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/comments?post=6094"}],"version-history":[{"count":1,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/posts\/6094\/revisions"}],"predecessor-version":[{"id":6096,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/posts\/6094\/revisions\/6096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/media\/6095"}],"wp:attachment":[{"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/media?parent=6094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/categories?post=6094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webs.ddca.se\/emprenderymas\/wp-json\/wp\/v2\/tags?post=6094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}